{"id":52979,"date":"2025-10-15T14:34:38","date_gmt":"2025-10-15T18:34:38","guid":{"rendered":"https:\/\/www.wes.org\/?p=52979"},"modified":"2025-10-15T14:36:09","modified_gmt":"2025-10-15T18:36:09","slug":"difference-entre-les-rapports-devaluation-des-titres-de-competences-document-par-document-et-cours-par-cours","status":"publish","type":"post","link":"https:\/\/www.wes.org\/fr\/resource-library\/blog\/conseils-sur-les-diplomes\/difference-entre-les-rapports-devaluation-des-titres-de-competences-document-par-document-et-cours-par-cours\/","title":{"rendered":"Diff\u00e9rence entre les rapports d\u2019\u00e9valuation des titres de comp\u00e9tences \u00ab Document par document \u00bb et \u00ab Cours par cours \u00bb"},"content":{"rendered":"<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-52922 size-large\" src=\"https:\/\/www.wes.org\/wp-content\/uploads\/2025\/10\/DxD-vs-CxC-blog-1024x683.jpg\" alt=\" Trois femmes professionnelles lisent un rapport d\u2019\u00e9valuation WES.\" width=\"1024\" height=\"683\" srcset=\"https:\/\/www.wes.org\/wp-content\/uploads\/2025\/10\/DxD-vs-CxC-blog-1024x683.jpg 1024w, https:\/\/www.wes.org\/wp-content\/uploads\/2025\/10\/DxD-vs-CxC-blog-300x200.jpg 300w, https:\/\/www.wes.org\/wp-content\/uploads\/2025\/10\/DxD-vs-CxC-blog-768x512.jpg 768w, https:\/\/www.wes.org\/wp-content\/uploads\/2025\/10\/DxD-vs-CxC-blog-541x362.jpg 541w, https:\/\/www.wes.org\/wp-content\/uploads\/2025\/10\/DxD-vs-CxC-blog.jpg 1350w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p><span data-contrast=\"auto\">Si vous envisagez une \u00e9valuation de vos titres de comp\u00e9tences, il est important de choisir le bon type de rapport en fonction de vos objectifs et de vos besoins. Chaque rapport est con\u00e7u pour accompagner diff\u00e9rents projets, comme les \u00e9tudes \u00e0 l\u2019\u00e9tranger, la candidature \u00e0 un emploi ou l\u2019immigration. En prenant le temps de comprendre les options qui s\u2019offrent \u00e0 vous, vous vous sentirez davantage confiant et pr\u00eat pour la suite.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">WES propose deux types de rapports standard d\u2019\u00e9valuation des dipl\u00f4mes\u00a0: <\/span><b><span data-contrast=\"auto\"> Document par document (DxD) <\/span><\/b><span data-contrast=\"auto\"> et<\/span><b><span data-contrast=\"auto\"> Cours par cours (CxC)<\/span><\/b><span data-contrast=\"auto\">.\u00a0<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<ul>\n<li aria-setsize=\"-1\" data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"1\" data-list-defn-props=\"{\" data-aria-posinset=\"1\" data-aria-level=\"1\"><b><span data-contrast=\"auto\">DxD\u00a0:<\/span><\/b><span data-contrast=\"auto\"> un rapport DxD standard identifie et d\u00e9crit chacun de vos dipl\u00f4mes que vous soumettez \u00e0 WES. Il fournit \u00e9galement le nom du titre de comp\u00e9tence \u00e9quivalent selon le syst\u00e8me \u00e9ducatif am\u00e9ricain ou canadien. <\/span><a href=\"https:\/\/www.wes.org\/wp-content\/uploads\/2017\/10\/sample-CE-US-dxd.png\"><b><span data-contrast=\"none\">Voir un exemple de rapport<\/span><\/b><\/a><span data-contrast=\"auto\">.<\/span><\/li>\n<li aria-setsize=\"-1\" data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"1\" data-list-defn-props=\"{\" data-aria-posinset=\"1\" data-aria-level=\"1\"><b><span data-contrast=\"auto\">CxC :<\/span><\/b><span data-contrast=\"auto\"> \u00c0 l\u2019instar du DxD, une \u00e9valuation CxC indique l\u2019\u00e9quivalence am\u00e9ricaine ou canadienne pour chaque titre de comp\u00e9tence que vous avez obtenu. Cependant, cette \u00e9valuation comprend \u00e9galement une analyse d\u00e9taill\u00e9e de chaque cours inscrit sur votre relev\u00e9 de notes. En plus d\u2019indiquer le dipl\u00f4me \u00e9quivalent, le rapport CxC convertit vos cr\u00e9dits semestriels et vos notes pour calculer une GPA sur une \u00e9chelle de 4,0. <\/span><a href=\"https:\/\/www.wes.org\/wp-content\/uploads\/2014\/04\/sample-CE-US-cxc-2021.png\"><b><span data-contrast=\"none\">Consultez un exemple de rapport<\/span><\/b><\/a><span data-contrast=\"auto\">.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/li>\n<\/ul>\n<p><span data-contrast=\"auto\">Pour un aper\u00e7u rapide, regardez la vid\u00e9o ci-dessous.\u00a0<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><iframe loading=\"lazy\" title=\"Quelle est la diff\u00e9rence entre une \u00e9valuation des qualifications DxD et CxC\u00a0?\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/3yogJ_c9DFo?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<h4><b><span data-contrast=\"auto\">Quel rapport choisir\u00a0?<\/span><\/b><span data-ccp-props=\"{}\">\u00a0<\/span><\/h4>\n<p><span data-contrast=\"auto\">En g\u00e9n\u00e9ral, un rapport DxD est adapt\u00e9 pour l\u2019immigration, l\u2019emploi et pour l\u2019admission \u00e0 un programme universitaire en premi\u00e8re ann\u00e9e<\/span><span data-contrast=\"auto\">.<\/span><span data-contrast=\"auto\"> Un rapport CxC peut \u00eatre exig\u00e9 par les organismes de r\u00e9glementation et pour les programmes d\u2019enseignement sup\u00e9rieur.\u00a0<\/span><span data-ccp-props=\"{\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Cependant, le type de rapport n\u00e9cessaire d\u00e9pendra de vos besoins sp\u00e9cifiques. C\u2019est pourquoi il est important de clarifier ce que vous esp\u00e9rez accomplir avec une \u00e9valuation des dipl\u00f4mes. Cela vous aidera \u00e0 mener des recherches appropri\u00e9es et \u00e0 vous poser les bonnes questions pour d\u00e9cider du <\/span><a href=\"https:\/\/www.wes.org\/fr\/resource-library\/blog\/conseils-sur-les-diplomes\/quel-est-le-meilleur-rapport-et-le-meilleur-forfait-devaluation-des-diplomes-pour-moi\/\"><b><span data-contrast=\"none\">rapport d\u2019\u00e9valuation des dipl\u00f4mes le plus adapt\u00e9 pour soutenir vos objectifs.<\/span><\/b><\/a><b><span data-contrast=\"auto\">\u00a0<\/span><\/b><\/p>\n<p><span data-ccp-props=\"{\">Si<\/span><span data-contrast=\"auto\"> vous envisagez de soumettre une \u00e9valuation des dipl\u00f4mes \u00e0 un \u00e9tablissement ou \u00e0 une organisation sp\u00e9cifique, nous vous recommandons vivement de contacter l\u2019entit\u00e9 concern\u00e9e et de vous assurer du type de rapport d\u2019\u00e9valuation requis.<\/span><span data-ccp-props=\"{\">\u00a0<\/span><\/p>\n<p><span class=\"TextRun SCXW55770999 BCX0\" lang=\"EN-US\" xml:lang=\"EN-US\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW55770999 BCX0\">Au fil de votre carri\u00e8re ou vos \u00e9tudes, il se peut qu\u2019\u00e0 un moment donn\u00e9, vous ayez besoin d\u2019un autre type de rapport. <\/span><span class=\"NormalTextRun SCXW55770999 BCX0\">Dans ce cas, <\/span><span class=\"NormalTextRun SCXW55770999 BCX0\">chaque ann\u00e9e, <\/span><span class=\"NormalTextRun SCXW55770999 BCX0\">des milliers de candidats passent d\u2019un rapport <\/span><span class=\"NormalTextRun SCXW55770999 BCX0\">DxD<\/span><span class=\"NormalTextRun SCXW55770999 BCX0\"> \u00e0 un rapport <\/span><span class=\"NormalTextRun SCXW55770999 BCX0\">CxC<\/span><span class=\"NormalTextRun SCXW55770999 BCX0\">, car ils <\/span><span class=\"NormalTextRun SCXW55770999 BCX0\">sont en qu\u00eate de <\/span><span class=\"NormalTextRun SCXW55770999 BCX0\">nouvelles opportunit\u00e9s. Apprenez-en davantage sur le<\/span> <\/span><strong><a class=\"Hyperlink SCXW55770999 BCX0\" href=\"https:\/\/www.wes.org\/fr\/resource-library\/blog\/conseils-sur-les-diplomes\/quest-ce-quune-evaluation-cours-par-cours-et-dans-quels-cas-pourrais-je-en-avoir-besoin\/\" target=\"_blank\" rel=\"noreferrer noopener\"><span class=\"TextRun Underlined SCXW55770999 BCX0\" lang=\"EN-US\" xml:lang=\"EN-US\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW55770999 BCX0\" data-ccp-charstyle=\"Hyperlink\">passage \u00e0 un rapport <\/span><span class=\"NormalTextRun SCXW55770999 BCX0\" data-ccp-charstyle=\"Hyperlink\">CxC<\/span><\/span><\/a><\/strong><span class=\"TextRun SCXW55770999 BCX0\" lang=\"EN-US\" xml:lang=\"EN-US\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW55770999 BCX0\">.<\/span><\/span><\/p>\n<h4><strong>Ressources suppl\u00e9mentaires<\/strong><\/h4>\n<p><span data-contrast=\"auto\"> Maintenant que vous avez compris les diff\u00e9rences entre les rapports DxD et CxC, vous \u00eates sur le point de choisir l\u2019\u00e9valuation des dipl\u00f4mes adapt\u00e9e \u00e0 votre parcours. Pour plus d\u2019informations sur les prix et les forfaits d\u2019\u00e9valuation, explorez notre <\/span><a href=\"https:\/\/www.wes.org\/fr\/evaluations-et-frais\/\"><b><span data-contrast=\"none\">page \u00c9valuations et frais<\/span><\/b><\/a><span data-contrast=\"auto\">.<\/span><\/p>\n<p><span data-contrast=\"auto\">Nous vous sugg\u00e9rons \u00e9galement d\u2019utiliser notre outil gratuit <\/span><a href=\"https:\/\/applications.wes.org\/required-documents\"><b><span data-contrast=\"none\">Documents requis<\/span><\/b><\/a><span data-contrast=\"auto\"> pour avoir un aper\u00e7u de ce dont nous avons besoin de votre part et de celle de votre \u00e9tablissement pour une \u00e9valuation. Il s\u2019agit d\u2019un excellent moyen de vous pr\u00e9parer et de vous organiser avant de <\/span><a href=\"https:\/\/applications.wes.org\/createaccount\"><b><span data-contrast=\"none\">soumettre votre candidature<\/span><\/b><\/a><span data-contrast=\"auto\">.<\/span><span data-ccp-props=\"{\">\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si vous envisagez une \u00e9valuation de vos titres de comp\u00e9tences, il est important de choisir le bon type de rapport en fonction de vos objectifs et de vos besoins. Chaque rapport est con\u00e7u pour accompagner diff\u00e9rents projets, comme les \u00e9tudes \u00e0 l\u2019\u00e9tranger, la candidature \u00e0 un emploi ou l\u2019immigration. En prenant le temps de comprendre [&hellip;]<\/p>\n","protected":false},"author":265,"featured_media":52924,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1408],"tags":[],"class_list":["post-52979","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-conseils-sur-les-diplomes"],"better_featured_image":{"id":52924,"alt_text":"","caption":"","description":"","media_type":"image","media_details":{"width":1350,"height":900,"file":"2025\/10\/DxD-vs-CxC-blog.jpg","filesize":700956,"sizes":{"medium":{"file":"DxD-vs-CxC-blog-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","filesize":18815,"source_url":"https:\/\/www.wes.org\/wp-content\/uploads\/2025\/10\/DxD-vs-CxC-blog-300x200.jpg"},"large":{"file":"DxD-vs-CxC-blog-1024x683.jpg","width":1024,"height":683,"mime-type":"image\/jpeg","filesize":112066,"source_url":"https:\/\/www.wes.org\/wp-content\/uploads\/2025\/10\/DxD-vs-CxC-blog-1024x683.jpg"},"thumbnail":{"file":"DxD-vs-CxC-blog-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":11254,"source_url":"https:\/\/www.wes.org\/wp-content\/uploads\/2025\/10\/DxD-vs-CxC-blog-150x150.jpg"},"medium_large":{"file":"DxD-vs-CxC-blog-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","filesize":71601,"source_url":"https:\/\/www.wes.org\/wp-content\/uploads\/2025\/10\/DxD-vs-CxC-blog-768x512.jpg"},"testimonial-thumb":{"file":"DxD-vs-CxC-blog-165x190.jpg","width":165,"height":190,"mime-type":"image\/jpeg","filesize":13746,"source_url":"https:\/\/www.wes.org\/wp-content\/uploads\/2025\/10\/DxD-vs-CxC-blog-165x190.jpg"},"carousel-post-thumb":{"file":"DxD-vs-CxC-blog-540x277.jpg","width":540,"height":277,"mime-type":"image\/jpeg","filesize":36958,"source_url":"https:\/\/www.wes.org\/wp-content\/uploads\/2025\/10\/DxD-vs-CxC-blog-540x277.jpg"},"col-profile-thumb":{"file":"DxD-vs-CxC-blog-195x195.jpg","width":195,"height":195,"mime-type":"image\/jpeg","filesize":15462,"source_url":"https:\/\/www.wes.org\/wp-content\/uploads\/2025\/10\/DxD-vs-CxC-blog-195x195.jpg"},"builder-feed-lg":{"file":"DxD-vs-CxC-blog-981x517.jpg","width":981,"height":517,"mime-type":"image\/jpeg","filesize":91276,"source_url":"https:\/\/www.wes.org\/wp-content\/uploads\/2025\/10\/DxD-vs-CxC-blog-981x517.jpg"},"team":{"file":"DxD-vs-CxC-blog-185x185.jpg","width":185,"height":185,"mime-type":"image\/jpeg","filesize":14580,"source_url":"https:\/\/www.wes.org\/wp-content\/uploads\/2025\/10\/DxD-vs-CxC-blog-185x185.jpg"},"people":{"file":"DxD-vs-CxC-blog-394x276.jpg","width":394,"height":276,"mime-type":"image\/jpeg","filesize":28533,"source_url":"https:\/\/www.wes.org\/wp-content\/uploads\/2025\/10\/DxD-vs-CxC-blog-394x276.jpg"},"insight":{"file":"DxD-vs-CxC-blog-541x362.jpg","width":541,"height":362,"mime-type":"image\/jpeg","filesize":43145,"source_url":"https:\/\/www.wes.org\/wp-content\/uploads\/2025\/10\/DxD-vs-CxC-blog-541x362.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"Milos Jokic","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":52979,"source_url":"https:\/\/www.wes.org\/wp-content\/uploads\/2025\/10\/DxD-vs-CxC-blog.jpg"},"acf":{"author_name":"WES Staff","author":false,"external_contributor":false,"sw_country":[],"column_1_heading":"","column_1_content_1":"","column_1_content_2":"","column_2_heading":"","column_3_heading":"","column_3_subheading_1":"","column_3_subheading_2":"","x_url":"","facebook_url":"","linkedin_url":"","youtube_url":"","subtitle":"","author_hide":false,"author_custom":"","link":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.2 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Diff\u00e9rence entre les rapports d\u2019\u00e9valuation des titres de comp\u00e9tences \u00ab Document par document \u00bb et \u00ab Cours par cours \u00bb - WES<\/title>\n<meta name=\"description\" content=\"Avant de commencer l\u2019\u00e9valuation de vos titres de comp\u00e9tences, prenez le temps de choisir le bon rapport. Il s\u2019agit d\u2019une \u00e9tape simple qui vous met sur la voie du succ\u00e8s.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.wes.org\/fr\/resource-library\/blog\/conseils-sur-les-diplomes\/difference-entre-les-rapports-devaluation-des-titres-de-competences-document-par-document-et-cours-par-cours\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Diff\u00e9rence entre les rapports d\u2019\u00e9valuation des titres de comp\u00e9tences \u00ab Document par document \u00bb et \u00ab Cours par cours \u00bb\" \/>\n<meta property=\"og:description\" content=\"Avant de commencer l\u2019\u00e9valuation de vos titres de comp\u00e9tences, prenez le temps de choisir le bon rapport. Il s\u2019agit d\u2019une \u00e9tape simple qui vous met sur la voie du succ\u00e8s.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.wes.org\/fr\/resource-library\/blog\/conseils-sur-les-diplomes\/difference-entre-les-rapports-devaluation-des-titres-de-competences-document-par-document-et-cours-par-cours\/\" \/>\n<meta property=\"og:site_name\" content=\"WES\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WorldEducationServices\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-15T18:34:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-15T18:36:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.wes.org\/wp-content\/uploads\/2025\/10\/DxD-vs-CxC-blog.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1350\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Patricia Thao\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WorldEdServices\" \/>\n<meta name=\"twitter:site\" content=\"@WorldEdServices\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Patricia Thao\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.wes.org\\\/fr\\\/resource-library\\\/blog\\\/conseils-sur-les-diplomes\\\/difference-entre-les-rapports-devaluation-des-titres-de-competences-document-par-document-et-cours-par-cours\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.wes.org\\\/fr\\\/resource-library\\\/blog\\\/conseils-sur-les-diplomes\\\/difference-entre-les-rapports-devaluation-des-titres-de-competences-document-par-document-et-cours-par-cours\\\/\"},\"author\":{\"name\":\"Patricia Thao\",\"@id\":\"https:\\\/\\\/www.wes.org\\\/fr\\\/#\\\/schema\\\/person\\\/f47b9f41634f9dd364a32a0443323d8e\"},\"headline\":\"Diff\u00e9rence entre les rapports d\u2019\u00e9valuation des titres de comp\u00e9tences \u00ab Document par document \u00bb et \u00ab Cours par cours \u00bb\",\"datePublished\":\"2025-10-15T18:34:38+00:00\",\"dateModified\":\"2025-10-15T18:36:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.wes.org\\\/fr\\\/resource-library\\\/blog\\\/conseils-sur-les-diplomes\\\/difference-entre-les-rapports-devaluation-des-titres-de-competences-document-par-document-et-cours-par-cours\\\/\"},\"wordCount\":574,\"publisher\":{\"@id\":\"https:\\\/\\\/www.wes.org\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.wes.org\\\/fr\\\/resource-library\\\/blog\\\/conseils-sur-les-diplomes\\\/difference-entre-les-rapports-devaluation-des-titres-de-competences-document-par-document-et-cours-par-cours\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.wes.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/DxD-vs-CxC-blog.jpg\",\"articleSection\":[\"Conseils sur les Dipl\u00f4mes\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.wes.org\\\/fr\\\/resource-library\\\/blog\\\/conseils-sur-les-diplomes\\\/difference-entre-les-rapports-devaluation-des-titres-de-competences-document-par-document-et-cours-par-cours\\\/\",\"url\":\"https:\\\/\\\/www.wes.org\\\/fr\\\/resource-library\\\/blog\\\/conseils-sur-les-diplomes\\\/difference-entre-les-rapports-devaluation-des-titres-de-competences-document-par-document-et-cours-par-cours\\\/\",\"name\":\"Diff\u00e9rence entre les rapports d\u2019\u00e9valuation des titres de comp\u00e9tences \u00ab Document par document \u00bb et \u00ab Cours par cours \u00bb - WES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.wes.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.wes.org\\\/fr\\\/resource-library\\\/blog\\\/conseils-sur-les-diplomes\\\/difference-entre-les-rapports-devaluation-des-titres-de-competences-document-par-document-et-cours-par-cours\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.wes.org\\\/fr\\\/resource-library\\\/blog\\\/conseils-sur-les-diplomes\\\/difference-entre-les-rapports-devaluation-des-titres-de-competences-document-par-document-et-cours-par-cours\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.wes.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/DxD-vs-CxC-blog.jpg\",\"datePublished\":\"2025-10-15T18:34:38+00:00\",\"dateModified\":\"2025-10-15T18:36:09+00:00\",\"description\":\"Avant de commencer l\u2019\u00e9valuation de vos titres de comp\u00e9tences, prenez le temps de choisir le bon rapport. Il s\u2019agit d\u2019une \u00e9tape simple qui vous met sur la voie du succ\u00e8s.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.wes.org\\\/fr\\\/resource-library\\\/blog\\\/conseils-sur-les-diplomes\\\/difference-entre-les-rapports-devaluation-des-titres-de-competences-document-par-document-et-cours-par-cours\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.wes.org\\\/fr\\\/resource-library\\\/blog\\\/conseils-sur-les-diplomes\\\/difference-entre-les-rapports-devaluation-des-titres-de-competences-document-par-document-et-cours-par-cours\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.wes.org\\\/fr\\\/resource-library\\\/blog\\\/conseils-sur-les-diplomes\\\/difference-entre-les-rapports-devaluation-des-titres-de-competences-document-par-document-et-cours-par-cours\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.wes.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/DxD-vs-CxC-blog.jpg\",\"contentUrl\":\"https:\\\/\\\/www.wes.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/DxD-vs-CxC-blog.jpg\",\"width\":1350,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.wes.org\\\/fr\\\/resource-library\\\/blog\\\/conseils-sur-les-diplomes\\\/difference-entre-les-rapports-devaluation-des-titres-de-competences-document-par-document-et-cours-par-cours\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.wes.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conseils sur les Dipl\u00f4mes\",\"item\":\"https:\\\/\\\/www.wes.org\\\/fr\\\/blog\\\/conseils-sur-les-diplomes\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Diff\u00e9rence entre les rapports d\u2019\u00e9valuation des titres de comp\u00e9tences \u00ab Document par document \u00bb et \u00ab Cours par cours \u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.wes.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.wes.org\\\/fr\\\/\",\"name\":\"World Education Services\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.wes.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.wes.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.wes.org\\\/fr\\\/#organization\",\"name\":\"World Education Services\",\"url\":\"https:\\\/\\\/www.wes.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.wes.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.wes.org\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/cropped-cropped-WES_Logo_RGB-Primary_Green-Clearspace-e1719869905447.png\",\"contentUrl\":\"https:\\\/\\\/www.wes.org\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/cropped-cropped-WES_Logo_RGB-Primary_Green-Clearspace-e1719869905447.png\",\"width\":512,\"height\":512,\"caption\":\"World Education Services\"},\"image\":{\"@id\":\"https:\\\/\\\/www.wes.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WorldEducationServices\\\/\",\"https:\\\/\\\/x.com\\\/WorldEdServices\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/worldeducationservices\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.wes.org\\\/fr\\\/#\\\/schema\\\/person\\\/f47b9f41634f9dd364a32a0443323d8e\",\"name\":\"Patricia Thao\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ea101294ad17795bd1f199d26c1f4d485246979892e3b44c09effc86201becd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ea101294ad17795bd1f199d26c1f4d485246979892e3b44c09effc86201becd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ea101294ad17795bd1f199d26c1f4d485246979892e3b44c09effc86201becd?s=96&d=mm&r=g\",\"caption\":\"Patricia Thao\"},\"sameAs\":[\"https:\\\/\\\/www.wes.org\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Diff\u00e9rence entre les rapports d\u2019\u00e9valuation des titres de comp\u00e9tences \u00ab Document par document \u00bb et \u00ab Cours par cours \u00bb - WES","description":"Avant de commencer l\u2019\u00e9valuation de vos titres de comp\u00e9tences, prenez le temps de choisir le bon rapport. Il s\u2019agit d\u2019une \u00e9tape simple qui vous met sur la voie du succ\u00e8s.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.wes.org\/fr\/resource-library\/blog\/conseils-sur-les-diplomes\/difference-entre-les-rapports-devaluation-des-titres-de-competences-document-par-document-et-cours-par-cours\/","og_locale":"fr_FR","og_type":"article","og_title":"Diff\u00e9rence entre les rapports d\u2019\u00e9valuation des titres de comp\u00e9tences \u00ab Document par document \u00bb et \u00ab Cours par cours \u00bb","og_description":"Avant de commencer l\u2019\u00e9valuation de vos titres de comp\u00e9tences, prenez le temps de choisir le bon rapport. Il s\u2019agit d\u2019une \u00e9tape simple qui vous met sur la voie du succ\u00e8s.","og_url":"https:\/\/www.wes.org\/fr\/resource-library\/blog\/conseils-sur-les-diplomes\/difference-entre-les-rapports-devaluation-des-titres-de-competences-document-par-document-et-cours-par-cours\/","og_site_name":"WES","article_publisher":"https:\/\/www.facebook.com\/WorldEducationServices\/","article_published_time":"2025-10-15T18:34:38+00:00","article_modified_time":"2025-10-15T18:36:09+00:00","og_image":[{"width":1350,"height":900,"url":"https:\/\/www.wes.org\/wp-content\/uploads\/2025\/10\/DxD-vs-CxC-blog.jpg","type":"image\/jpeg"}],"author":"Patricia Thao","twitter_card":"summary_large_image","twitter_creator":"@WorldEdServices","twitter_site":"@WorldEdServices","twitter_misc":{"\u00c9crit par":"Patricia Thao","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.wes.org\/fr\/resource-library\/blog\/conseils-sur-les-diplomes\/difference-entre-les-rapports-devaluation-des-titres-de-competences-document-par-document-et-cours-par-cours\/#article","isPartOf":{"@id":"https:\/\/www.wes.org\/fr\/resource-library\/blog\/conseils-sur-les-diplomes\/difference-entre-les-rapports-devaluation-des-titres-de-competences-document-par-document-et-cours-par-cours\/"},"author":{"name":"Patricia Thao","@id":"https:\/\/www.wes.org\/fr\/#\/schema\/person\/f47b9f41634f9dd364a32a0443323d8e"},"headline":"Diff\u00e9rence entre les rapports d\u2019\u00e9valuation des titres de comp\u00e9tences \u00ab Document par document \u00bb et \u00ab Cours par cours \u00bb","datePublished":"2025-10-15T18:34:38+00:00","dateModified":"2025-10-15T18:36:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.wes.org\/fr\/resource-library\/blog\/conseils-sur-les-diplomes\/difference-entre-les-rapports-devaluation-des-titres-de-competences-document-par-document-et-cours-par-cours\/"},"wordCount":574,"publisher":{"@id":"https:\/\/www.wes.org\/fr\/#organization"},"image":{"@id":"https:\/\/www.wes.org\/fr\/resource-library\/blog\/conseils-sur-les-diplomes\/difference-entre-les-rapports-devaluation-des-titres-de-competences-document-par-document-et-cours-par-cours\/#primaryimage"},"thumbnailUrl":"https:\/\/www.wes.org\/wp-content\/uploads\/2025\/10\/DxD-vs-CxC-blog.jpg","articleSection":["Conseils sur les Dipl\u00f4mes"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.wes.org\/fr\/resource-library\/blog\/conseils-sur-les-diplomes\/difference-entre-les-rapports-devaluation-des-titres-de-competences-document-par-document-et-cours-par-cours\/","url":"https:\/\/www.wes.org\/fr\/resource-library\/blog\/conseils-sur-les-diplomes\/difference-entre-les-rapports-devaluation-des-titres-de-competences-document-par-document-et-cours-par-cours\/","name":"Diff\u00e9rence entre les rapports d\u2019\u00e9valuation des titres de comp\u00e9tences \u00ab Document par document \u00bb et \u00ab Cours par cours \u00bb - WES","isPartOf":{"@id":"https:\/\/www.wes.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.wes.org\/fr\/resource-library\/blog\/conseils-sur-les-diplomes\/difference-entre-les-rapports-devaluation-des-titres-de-competences-document-par-document-et-cours-par-cours\/#primaryimage"},"image":{"@id":"https:\/\/www.wes.org\/fr\/resource-library\/blog\/conseils-sur-les-diplomes\/difference-entre-les-rapports-devaluation-des-titres-de-competences-document-par-document-et-cours-par-cours\/#primaryimage"},"thumbnailUrl":"https:\/\/www.wes.org\/wp-content\/uploads\/2025\/10\/DxD-vs-CxC-blog.jpg","datePublished":"2025-10-15T18:34:38+00:00","dateModified":"2025-10-15T18:36:09+00:00","description":"Avant de commencer l\u2019\u00e9valuation de vos titres de comp\u00e9tences, prenez le temps de choisir le bon rapport. Il s\u2019agit d\u2019une \u00e9tape simple qui vous met sur la voie du succ\u00e8s.","breadcrumb":{"@id":"https:\/\/www.wes.org\/fr\/resource-library\/blog\/conseils-sur-les-diplomes\/difference-entre-les-rapports-devaluation-des-titres-de-competences-document-par-document-et-cours-par-cours\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.wes.org\/fr\/resource-library\/blog\/conseils-sur-les-diplomes\/difference-entre-les-rapports-devaluation-des-titres-de-competences-document-par-document-et-cours-par-cours\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.wes.org\/fr\/resource-library\/blog\/conseils-sur-les-diplomes\/difference-entre-les-rapports-devaluation-des-titres-de-competences-document-par-document-et-cours-par-cours\/#primaryimage","url":"https:\/\/www.wes.org\/wp-content\/uploads\/2025\/10\/DxD-vs-CxC-blog.jpg","contentUrl":"https:\/\/www.wes.org\/wp-content\/uploads\/2025\/10\/DxD-vs-CxC-blog.jpg","width":1350,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/www.wes.org\/fr\/resource-library\/blog\/conseils-sur-les-diplomes\/difference-entre-les-rapports-devaluation-des-titres-de-competences-document-par-document-et-cours-par-cours\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.wes.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Conseils sur les Dipl\u00f4mes","item":"https:\/\/www.wes.org\/fr\/blog\/conseils-sur-les-diplomes\/"},{"@type":"ListItem","position":3,"name":"Diff\u00e9rence entre les rapports d\u2019\u00e9valuation des titres de comp\u00e9tences \u00ab Document par document \u00bb et \u00ab Cours par cours \u00bb"}]},{"@type":"WebSite","@id":"https:\/\/www.wes.org\/fr\/#website","url":"https:\/\/www.wes.org\/fr\/","name":"World Education Services","description":"","publisher":{"@id":"https:\/\/www.wes.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.wes.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.wes.org\/fr\/#organization","name":"World Education Services","url":"https:\/\/www.wes.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.wes.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.wes.org\/wp-content\/uploads\/2024\/07\/cropped-cropped-WES_Logo_RGB-Primary_Green-Clearspace-e1719869905447.png","contentUrl":"https:\/\/www.wes.org\/wp-content\/uploads\/2024\/07\/cropped-cropped-WES_Logo_RGB-Primary_Green-Clearspace-e1719869905447.png","width":512,"height":512,"caption":"World Education Services"},"image":{"@id":"https:\/\/www.wes.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WorldEducationServices\/","https:\/\/x.com\/WorldEdServices","https:\/\/www.linkedin.com\/company\/worldeducationservices\/"]},{"@type":"Person","@id":"https:\/\/www.wes.org\/fr\/#\/schema\/person\/f47b9f41634f9dd364a32a0443323d8e","name":"Patricia Thao","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/2ea101294ad17795bd1f199d26c1f4d485246979892e3b44c09effc86201becd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2ea101294ad17795bd1f199d26c1f4d485246979892e3b44c09effc86201becd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2ea101294ad17795bd1f199d26c1f4d485246979892e3b44c09effc86201becd?s=96&d=mm&r=g","caption":"Patricia Thao"},"sameAs":["https:\/\/www.wes.org"]}]}},"wpml_current_locale":"fr_FR","wpml_translations":[{"locale":"en_US","id":52921,"post_title":"The Difference Between Document-by-Document and Course-by-Course Credential Evaluation Reports","href":"https:\/\/www.wes.org\/the-difference-between-document-by-document-and-course-by-course-credential-evaluation-reports\/"}],"_links":{"self":[{"href":"https:\/\/www.wes.org\/fr\/wp-json\/wp\/v2\/posts\/52979","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wes.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.wes.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.wes.org\/fr\/wp-json\/wp\/v2\/users\/265"}],"replies":[{"embeddable":true,"href":"https:\/\/www.wes.org\/fr\/wp-json\/wp\/v2\/comments?post=52979"}],"version-history":[{"count":0,"href":"https:\/\/www.wes.org\/fr\/wp-json\/wp\/v2\/posts\/52979\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.wes.org\/fr\/wp-json\/wp\/v2\/media\/52924"}],"wp:attachment":[{"href":"https:\/\/www.wes.org\/fr\/wp-json\/wp\/v2\/media?parent=52979"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.wes.org\/fr\/wp-json\/wp\/v2\/categories?post=52979"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.wes.org\/fr\/wp-json\/wp\/v2\/tags?post=52979"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}